{"id":3900,"date":"2026-01-24T14:53:25","date_gmt":"2026-01-24T13:53:25","guid":{"rendered":"https:\/\/test4.praktijk.nl\/?post_type=medewerkers&#038;p=3900"},"modified":"2026-01-24T14:53:25","modified_gmt":"2026-01-24T13:53:25","slug":"sabine-vuister","status":"publish","type":"medewerkers","link":"https:\/\/huisartsen.gcschalkwijk.nl\/tr\/medewerkers\/sabine-vuister\/","title":{"rendered":"Sabine Vuister"},"template":"","meta":{"functie":"Huisarts - SCEN arts","aanwezig_op":{"Ma":"true","Di":"true","Wo":"true","Do":"true","Vr":"false"},"foto-medewerker":"https:\/\/huisartsen.gcschalkwijk.nl\/wp-content\/uploads\/2023\/01\/Sabine-Vuister-small.jpg"},"medewerkerspraktijk":[24],"class_list":["post-3900","medewerkers","type-medewerkers","status-publish","hentry","medewerkerspraktijk-huisartsen"],"_links":{"self":[{"href":"https:\/\/huisartsen.gcschalkwijk.nl\/tr\/wp-json\/wp\/v2\/medewerkers\/3900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huisartsen.gcschalkwijk.nl\/tr\/wp-json\/wp\/v2\/medewerkers"}],"about":[{"href":"https:\/\/huisartsen.gcschalkwijk.nl\/tr\/wp-json\/wp\/v2\/types\/medewerkers"}],"version-history":[{"count":2,"href":"https:\/\/huisartsen.gcschalkwijk.nl\/tr\/wp-json\/wp\/v2\/medewerkers\/3900\/revisions"}],"predecessor-version":[{"id":3902,"href":"https:\/\/huisartsen.gcschalkwijk.nl\/tr\/wp-json\/wp\/v2\/medewerkers\/3900\/revisions\/3902"}],"wp:attachment":[{"href":"https:\/\/huisartsen.gcschalkwijk.nl\/tr\/wp-json\/wp\/v2\/media?parent=3900"}],"wp:term":[{"taxonomy":"medewerkerspraktijk","embeddable":true,"href":"https:\/\/huisartsen.gcschalkwijk.nl\/tr\/wp-json\/wp\/v2\/medewerkerspraktijk?post=3900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}